{"id":1587,"date":"2022-05-25T13:55:43","date_gmt":"2022-05-25T11:55:43","guid":{"rendered":"https:\/\/gestuet-neuenhof.jam-digital.de\/?post_type=blogbeitrag&#038;p=1587"},"modified":"2022-05-25T13:55:43","modified_gmt":"2022-05-25T11:55:43","slug":"bettenrode-auch-der-sieg-in-der-bucha-quali-der-6-jaehrigen-geht-an-einen-escolar-sohn","status":"publish","type":"blogbeitrag","link":"https:\/\/www.gestuet-neuenhof.de\/en\/blog-post\/bettenrode-auch-der-sieg-in-der-bucha-quali-der-6-jaehrigen-geht-an-einen-escolar-sohn\/","title":{"rendered":"Bettenrode: Auch der Sieg in der BuCha-Quali der 6-j\u00e4hrigen geht an einen Escolar Sohn"},"featured_media":1502,"template":"","class_list":["post-1587","blogbeitrag","type-blogbeitrag","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.gestuet-neuenhof.de\/en\/wp-json\/wp\/v2\/blogbeitrag\/1587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gestuet-neuenhof.de\/en\/wp-json\/wp\/v2\/blogbeitrag"}],"about":[{"href":"https:\/\/www.gestuet-neuenhof.de\/en\/wp-json\/wp\/v2\/types\/blogbeitrag"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gestuet-neuenhof.de\/en\/wp-json\/wp\/v2\/media\/1502"}],"wp:attachment":[{"href":"https:\/\/www.gestuet-neuenhof.de\/en\/wp-json\/wp\/v2\/media?parent=1587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}